{"id":50292,"date":"2025-12-19T20:30:36","date_gmt":"2025-12-19T19:30:36","guid":{"rendered":"https:\/\/www.gold.fr\/news\/?p=50292"},"modified":"2025-12-22T11:37:15","modified_gmt":"2025-12-22T10:37:15","slug":"les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit","status":"publish","type":"post","link":"https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/","title":{"rendered":"Les banques centrales accumulent, mais pas pour les raisons que l\u2019on croit"},"content":{"rendered":"<p data-start=\"582\" data-end=\"861\">Depuis trois ans, un mouvement inhabituel s\u2019installe dans les statistiques mon\u00e9taires mondiales. Les banques centrales ach\u00e8tent massivement \u2014 et surtout <strong data-start=\"735\" data-end=\"750\">durablement<\/strong>.<br \/>\nDe l&rsquo;or, mais pas que.<br data-start=\"751\" data-end=\"754\" \/>Pas sur quelques mois, mais <strong data-start=\"782\" data-end=\"819\">sur plusieurs ann\u00e9es cons\u00e9cutives<\/strong>, \u00e0 un niveau in\u00e9dit depuis des d\u00e9cennies.<\/p>\n<p data-start=\"863\" data-end=\"889\">Et ce n\u2019est pas un d\u00e9tail.<\/p>\n<h2 data-start=\"891\" data-end=\"942\">Des achats d\u2019or \u00e0 un niveau historiquement \u00e9lev\u00e9<\/h2>\n<p data-start=\"944\" data-end=\"1023\">Selon les donn\u00e9es du <strong data-start=\"965\" data-end=\"987\">World Gold Council<\/strong>, les banques centrales ont achet\u00e9 :<\/p>\n<ul data-start=\"1025\" data-end=\"1192\">\n<li data-start=\"1025\" data-end=\"1066\">\n<p data-start=\"1027\" data-end=\"1066\"><strong data-start=\"1027\" data-end=\"1064\">environ 1 080 tonnes d\u2019or en 2022<\/strong><\/p>\n<\/li>\n<li data-start=\"1067\" data-end=\"1110\">\n<p data-start=\"1069\" data-end=\"1110\"><strong data-start=\"1069\" data-end=\"1108\">un peu plus de 1 030 tonnes en 2023<\/strong><\/p>\n<\/li>\n<li data-start=\"1111\" data-end=\"1192\">\n<p data-start=\"1113\" data-end=\"1192\"><strong data-start=\"1113\" data-end=\"1155\">plus de 1 000 tonnes \u00e0 nouveau en 2024<\/strong>, selon les estimations consolid\u00e9es<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"1194\" data-end=\"1356\">C\u2019est <strong data-start=\"1200\" data-end=\"1276\">trois ann\u00e9es cons\u00e9cutives au-dessus du seuil symbolique des 1 000 tonnes<\/strong>, un niveau jamais observ\u00e9 de mani\u00e8re aussi persistante dans l\u2019histoire moderne.<\/p>\n<p data-start=\"1358\" data-end=\"1478\">\u00c0 titre de comparaison, sur la d\u00e9cennie pr\u00e9c\u00e9dente, les achats annuels tournaient plut\u00f4t autour de <strong data-start=\"1457\" data-end=\"1477\">400 \u00e0 600 tonnes<\/strong>.<\/p>\n<p data-start=\"1480\" data-end=\"1566\">Autrement dit : le rythme actuel est <strong data-start=\"1522\" data-end=\"1565\">pr\u00e8s du double de la moyenne historique<\/strong>.<\/p>\n<h2>Quelles banques centrales sont \u00e0 l\u2019origine de ce mouvement ?<\/h2>\n<p data-start=\"1633\" data-end=\"1767\">Les achats ne sont pas r\u00e9partis uniform\u00e9ment. Ils proviennent majoritairement de pays qui cherchent \u00e0 <strong data-start=\"1735\" data-end=\"1766\">r\u00e9\u00e9quilibrer leurs r\u00e9serves<\/strong>.<\/p>\n<p data-start=\"1769\" data-end=\"1846\">Parmi les acheteurs les plus actifs ces derni\u00e8res ann\u00e9es figurent notamment :<\/p>\n<ul data-start=\"1848\" data-end=\"2260\">\n<li data-start=\"1848\" data-end=\"1954\">\n<p data-start=\"1850\" data-end=\"1954\"><strong data-start=\"1850\" data-end=\"1862\">la Chine<\/strong>, qui a repris officiellement ses achats fin 2022 et les a poursuivis de mani\u00e8re r\u00e9guli\u00e8re<\/p>\n<\/li>\n<li data-start=\"1955\" data-end=\"2021\">\n<p data-start=\"1957\" data-end=\"2021\"><strong data-start=\"1957\" data-end=\"1971\">la Pologne<\/strong>, devenue l\u2019un des plus gros acheteurs europ\u00e9ens avec des achats significatifs \u2014 pr\u00e8s de <strong data-start=\"1564\" data-end=\"1603\">50 tonnes d\u00e8s le 1er trimestre 2025<\/strong>, d\u00e9passant m\u00eame certains achats chinois sur toute l\u2019ann\u00e9e pr\u00e9c\u00e9dente.<\/p>\n<\/li>\n<li data-start=\"2022\" data-end=\"2104\">\n<p data-start=\"2024\" data-end=\"2104\"><strong data-start=\"2024\" data-end=\"2038\">la Turquie<\/strong>, malgr\u00e9 des ventes ponctuelles li\u00e9es \u00e0 des contraintes internes<\/p>\n<\/li>\n<li data-start=\"2105\" data-end=\"2170\">\n<p data-start=\"2107\" data-end=\"2170\"><strong data-start=\"2107\" data-end=\"2117\">l\u2019Inde<\/strong>, dans une logique de diversification de long terme<\/p>\n<\/li>\n<li data-start=\"2171\" data-end=\"2260\">\n<p data-start=\"2173\" data-end=\"2260\"><strong data-start=\"2173\" data-end=\"2186\">Singapour<\/strong>, <strong data-start=\"2188\" data-end=\"2205\">le Kazakhstan<\/strong>, <strong data-start=\"2207\" data-end=\"2232\">la R\u00e9publique tch\u00e8que<\/strong> ou encore <strong data-start=\"2243\" data-end=\"2260\">l\u2019Ouzb\u00e9kistan<\/strong><\/p>\n<\/li>\n<\/ul>\n<p data-start=\"2262\" data-end=\"2428\">Ce point est essentiel : ce mouvement ne concerne pas uniquement des pays \u00ab en crise \u00bb, mais aussi des \u00e9conomies stables, int\u00e9gr\u00e9es au syst\u00e8me financier mondial.<\/p>\n<h2 data-start=\"2430\" data-end=\"2500\">Si ce n\u2019\u00e9tait que l\u2019inflation, d\u2019autres outils seraient privil\u00e9gi\u00e9s<\/h2>\n<p data-start=\"2502\" data-end=\"2657\">On explique souvent ces achats par la lutte contre l\u2019inflation. Mais si c\u2019\u00e9tait la seule motivation, les banques centrales disposeraient d\u2019autres leviers :<\/p>\n<ul data-start=\"2659\" data-end=\"2831\">\n<li data-start=\"2659\" data-end=\"2699\">\n<p data-start=\"2661\" data-end=\"2699\">obligations index\u00e9es sur l\u2019inflation<\/p>\n<\/li>\n<li data-start=\"2700\" data-end=\"2738\">\n<p data-start=\"2702\" data-end=\"2738\">ajustements de r\u00e9serves en devises<\/p>\n<\/li>\n<li data-start=\"2739\" data-end=\"2777\">\n<p data-start=\"2741\" data-end=\"2777\">modifications de politique de taux<\/p>\n<\/li>\n<li data-start=\"2778\" data-end=\"2831\">\n<p data-start=\"2780\" data-end=\"2831\">arbitrages entre monnaies (dollar, euro, yen, yuan)<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"2833\" data-end=\"2879\">Or, ce n\u2019est pas ce qu\u2019elles font en priorit\u00e9.<\/p>\n<p data-start=\"2881\" data-end=\"2975\">Elles <strong data-start=\"2887\" data-end=\"2924\">augmentent la part d\u2019actifs r\u00e9els<\/strong>, et en particulier d\u2019actifs <strong data-start=\"2953\" data-end=\"2974\">sans contrepartie<\/strong>.<\/p>\n<h2 data-start=\"2977\" data-end=\"3022\">Quels actifs accumulent-elles r\u00e9ellement ?<\/h2>\n<p data-start=\"3024\" data-end=\"3095\">Il faut \u00eatre clair : <strong data-start=\"3050\" data-end=\"3094\">l\u2019or est de tr\u00e8s loin l\u2019actif privil\u00e9gi\u00e9<\/strong>.<\/p>\n<p data-start=\"3097\" data-end=\"3294\">Les banques centrales <strong data-start=\"3119\" data-end=\"3158\">n\u2019ach\u00e8tent pas massivement l\u2019argent<\/strong>, ni d\u2019autres m\u00e9taux pr\u00e9cieux.<br data-start=\"3188\" data-end=\"3191\" \/>L\u2019argent reste avant tout un m\u00e9tal industriel, plus volatil, moins adapt\u00e9 au r\u00f4le de r\u00e9serve mon\u00e9taire.<\/p>\n<p data-start=\"3296\" data-end=\"3390\">Elles n\u2019accumulent pas non plus de mati\u00e8res premi\u00e8res physiques comme le cuivre ou le p\u00e9trole.<\/p>\n<p data-start=\"3392\" data-end=\"3421\">Leur logique est diff\u00e9rente :<\/p>\n<ul data-start=\"3422\" data-end=\"3612\">\n<li data-start=\"3422\" data-end=\"3460\">\n<p data-start=\"3424\" data-end=\"3460\">un actif <strong data-start=\"3433\" data-end=\"3460\">universellement reconnu<\/strong><\/p>\n<\/li>\n<li data-start=\"3461\" data-end=\"3495\">\n<p data-start=\"3463\" data-end=\"3495\"><strong data-start=\"3463\" data-end=\"3495\">liquide \u00e0 l\u2019\u00e9chelle mondiale<\/strong><\/p>\n<\/li>\n<li data-start=\"3496\" data-end=\"3523\">\n<p data-start=\"3498\" data-end=\"3523\"><strong data-start=\"3498\" data-end=\"3523\">sans risque de d\u00e9faut<\/strong><\/p>\n<\/li>\n<li data-start=\"3524\" data-end=\"3555\">\n<p data-start=\"3526\" data-end=\"3555\"><strong data-start=\"3526\" data-end=\"3555\">hors syst\u00e8me de sanctions<\/strong><\/p>\n<\/li>\n<li data-start=\"3556\" data-end=\"3612\">\n<p data-start=\"3558\" data-end=\"3612\"><strong data-start=\"3558\" data-end=\"3612\">ind\u00e9pendant de toute politique mon\u00e9taire \u00e9trang\u00e8re<\/strong><\/p>\n<\/li>\n<\/ul>\n<p data-start=\"3614\" data-end=\"3660\">Sur ce terrain, <strong data-start=\"3630\" data-end=\"3659\">l\u2019or n\u2019a pas d\u2019\u00e9quivalent<\/strong>.<\/p>\n<h2 data-start=\"3662\" data-end=\"3719\">Le vrai enjeu : la confiance dans le syst\u00e8me mon\u00e9taire<\/h2>\n<p data-start=\"3721\" data-end=\"3846\">Ce que r\u00e9v\u00e8lent ces chiffres, ce n\u2019est pas la peur d\u2019une crise imm\u00e9diate, mais une <strong data-start=\"3804\" data-end=\"3845\">\u00e9rosion de la confiance de long terme<\/strong>.<\/p>\n<p data-start=\"3848\" data-end=\"4093\">Endettement public record, cr\u00e9ation mon\u00e9taire prolong\u00e9e, tensions g\u00e9opolitiques, usage croissant des sanctions financi\u00e8res :<br data-start=\"3972\" data-end=\"3975\" \/>les banques centrales cherchent \u00e0 <strong data-start=\"4009\" data-end=\"4036\">r\u00e9duire leur d\u00e9pendance<\/strong> \u00e0 un syst\u00e8me qu\u2019elles jugent plus fragile qu\u2019auparavant.<\/p>\n<p data-start=\"4095\" data-end=\"4323\">Comme l\u2019expliquent r\u00e9guli\u00e8rement les experts du <strong data-start=\"4143\" data-end=\"4186\">Comptoir National de l\u2019Or (<a class=\"decorated-link\" href=\"http:\/\/www.gold.fr\" target=\"_new\" rel=\"noopener\" data-start=\"4172\" data-end=\"4183\">www.gold.fr<\/a>)<\/strong>, ces d\u00e9cisions s\u2019inscrivent dans une logique de <strong data-start=\"4235\" data-end=\"4275\">s\u00e9curisation sur plusieurs d\u00e9cennies<\/strong>, pas dans une r\u00e9action tactique de court terme.<\/p>\n<a href=\"https:\/\/support.gold.fr\/fr\/livreblanc-investir-dans-l-or-gdn2024-sj\" target=\"_blank\" class=\"goldCTA\">\n    <img decoding=\"async\" src=\"https:\/\/www.gold.fr\/news\/wp-content\/uploads\/2024\/09\/Couverture-LB-quel-budget-pour-investir-dans-lor.png\" alt=\"\" \/>    <div class=\"rightPart\">\n        <div class=\"content\">\n            <\/p>\n<p>Vous souhaitez investir dans l&rsquo;or ?<\/p>\n<p>Vous h\u00e9sitez \u00e0 diversifier votre portefeuille ? Pourquoi ne pas investir dans l&rsquo;or ? Notre guide vous permettra d&rsquo;affiner votre r\u00e9flexion gr\u00e2ce \u00e0 des exemples de pi\u00e8ces et lingots d&rsquo;or que vous pourriez acqu\u00e9rir avec votre budget.<\/p>\n<p>        <\/div>\n                <span class=\"button\">Je souhaite investir dans l'or !<\/span>\n            <\/div>\n<\/a>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Depuis trois ans, un mouvement inhabituel s\u2019installe dans les statistiques mon\u00e9taires mondiales. Les banques centrales ach\u00e8tent massivement \u2014 et surtout durablement. De l&rsquo;or, mais pas que.Pas sur quelques mois, mais sur plusieurs ann\u00e9es cons\u00e9cutives, \u00e0 un [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":50293,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mbp_gutenberg_autopost":false,"_pgmb_is_evergreen":false,"_pgmb_ap_template_id":0,"footnotes":""},"categories":[2558],"tags":[],"ppma_author":[2565],"class_list":["post-50292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les banques centrales accumulent, mais pas pour les raisons que l\u2019on croit - Gold.fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les banques centrales accumulent, mais pas pour les raisons que l\u2019on croit - Gold.fr\" \/>\n<meta property=\"og:description\" content=\"Depuis trois ans, un mouvement inhabituel s\u2019installe dans les statistiques mon\u00e9taires mondiales. Les banques centrales ach\u00e8tent massivement \u2014 et surtout durablement. De l&rsquo;or, mais pas que.Pas sur quelques mois, mais sur plusieurs ann\u00e9es cons\u00e9cutives, \u00e0 un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/\" \/>\n<meta property=\"og:site_name\" content=\"Gold.fr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Goldfr\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-19T19:30:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-22T10:37:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gold.fr\/news\/wp-content\/uploads\/2025\/12\/ChatGPT-Image-19-dec.-2025-20_29_55-1024x683.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Comptoir National de l&#039;Or\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comptoir National de l&#039;Or\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/2025\\\/12\\\/19\\\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/2025\\\/12\\\/19\\\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\\\/\"},\"author\":{\"name\":\"Comptoir National de l'Or\",\"@id\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/#\\\/schema\\\/person\\\/070491b4b4fb7671bf59b3be20302ce9\"},\"headline\":\"Les banques centrales accumulent, mais pas pour les raisons que l\u2019on croit\",\"datePublished\":\"2025-12-19T19:30:36+00:00\",\"dateModified\":\"2025-12-22T10:37:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/2025\\\/12\\\/19\\\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\\\/\"},\"wordCount\":732,\"image\":{\"@id\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/2025\\\/12\\\/19\\\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ChatGPT-Image-19-dec.-2025-20_29_55.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/2025\\\/12\\\/19\\\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\\\/\",\"url\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/2025\\\/12\\\/19\\\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\\\/\",\"name\":\"Les banques centrales accumulent, mais pas pour les raisons que l\u2019on croit - Gold.fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/2025\\\/12\\\/19\\\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/2025\\\/12\\\/19\\\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ChatGPT-Image-19-dec.-2025-20_29_55.png\",\"datePublished\":\"2025-12-19T19:30:36+00:00\",\"dateModified\":\"2025-12-22T10:37:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/#\\\/schema\\\/person\\\/070491b4b4fb7671bf59b3be20302ce9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/2025\\\/12\\\/19\\\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gold.fr\\\/news\\\/2025\\\/12\\\/19\\\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/2025\\\/12\\\/19\\\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ChatGPT-Image-19-dec.-2025-20_29_55.png\",\"contentUrl\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ChatGPT-Image-19-dec.-2025-20_29_55.png\",\"width\":1536,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/2025\\\/12\\\/19\\\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.gold.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9s\",\"item\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les banques centrales accumulent, mais pas pour les raisons que l\u2019on croit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/\",\"name\":\"Gold.fr\",\"description\":\"Actualit\u00e9s de l&#039;Or et des m\u00e9taux pr\u00e9cieux\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gold.fr\\\/news\\\/#\\\/schema\\\/person\\\/070491b4b4fb7671bf59b3be20302ce9\",\"name\":\"Comptoir National de l'Or\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a2867fd5abe37bed95d5a65e9d58f01756e11efc68af9888dfc50cfa7f65948?s=96&d=mm&r=gb490554db0a38188709de567aa58480d\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a2867fd5abe37bed95d5a65e9d58f01756e11efc68af9888dfc50cfa7f65948?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a2867fd5abe37bed95d5a65e9d58f01756e11efc68af9888dfc50cfa7f65948?s=96&d=mm&r=g\",\"caption\":\"Comptoir National de l'Or\"},\"description\":\"Notre r\u00e9daction est constitu\u00e9e de membres experts dans les m\u00e9tiers de l'\u00e9conomie et la gestion, des Responsables d'agence Comptoir National de l'Or, des analystes financiers qui publient r\u00e9guli\u00e8rement des \u00e9tudes sur les politiques des banques centrales, le cours de l'or, prix de l'or, cours de l'argent, prix de l'argent, cours du platine, cours du palladium,... la situation en zone euro et l'impact de la strat\u00e9gie mon\u00e9taire de la FED. Notre \u00e9quipe scrute \u00e9galement une information plus g\u00e9n\u00e9raliste \u00e0 la recherche d'actualit\u00e9 \\\"p\u00e9pite\\\" \u00e0 vous partager. Depuis 5 ans, nous avons publi\u00e9 un peu plus de 4000 articles qui s'adressent \u00e0 un public large et vari\u00e9 ayant pour objectif de satisfaire votre curiosit\u00e9 et de partager avec vous une certaine fascination pour le m\u00e9tal jaune, le rachat d'or, et pour ceux qui veulent investir dans l'or, vendre leur or tout simplement en savoir plus... Pour tous vos achat or et argent, n'h\u00e9sitez pas \u00e0 prendre rendez-vous dans l'un de nos nombreux comptoirs.\",\"sameAs\":[\"https:\\\/\\\/www.gold.fr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les banques centrales accumulent, mais pas pour les raisons que l\u2019on croit - Gold.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/","og_locale":"fr_FR","og_type":"article","og_title":"Les banques centrales accumulent, mais pas pour les raisons que l\u2019on croit - Gold.fr","og_description":"Depuis trois ans, un mouvement inhabituel s\u2019installe dans les statistiques mon\u00e9taires mondiales. Les banques centrales ach\u00e8tent massivement \u2014 et surtout durablement. De l&rsquo;or, mais pas que.Pas sur quelques mois, mais sur plusieurs ann\u00e9es cons\u00e9cutives, \u00e0 un [&hellip;]","og_url":"https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/","og_site_name":"Gold.fr","article_publisher":"https:\/\/www.facebook.com\/Goldfr\/","article_published_time":"2025-12-19T19:30:36+00:00","article_modified_time":"2025-12-22T10:37:15+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.gold.fr\/news\/wp-content\/uploads\/2025\/12\/ChatGPT-Image-19-dec.-2025-20_29_55-1024x683.png","type":"image\/png"}],"author":"Comptoir National de l'Or","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Comptoir National de l'Or","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/#article","isPartOf":{"@id":"https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/"},"author":{"name":"Comptoir National de l'Or","@id":"https:\/\/www.gold.fr\/news\/#\/schema\/person\/070491b4b4fb7671bf59b3be20302ce9"},"headline":"Les banques centrales accumulent, mais pas pour les raisons que l\u2019on croit","datePublished":"2025-12-19T19:30:36+00:00","dateModified":"2025-12-22T10:37:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/"},"wordCount":732,"image":{"@id":"https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gold.fr\/news\/wp-content\/uploads\/2025\/12\/ChatGPT-Image-19-dec.-2025-20_29_55.png","articleSection":["News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/","url":"https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/","name":"Les banques centrales accumulent, mais pas pour les raisons que l\u2019on croit - Gold.fr","isPartOf":{"@id":"https:\/\/www.gold.fr\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/#primaryimage"},"image":{"@id":"https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gold.fr\/news\/wp-content\/uploads\/2025\/12\/ChatGPT-Image-19-dec.-2025-20_29_55.png","datePublished":"2025-12-19T19:30:36+00:00","dateModified":"2025-12-22T10:37:15+00:00","author":{"@id":"https:\/\/www.gold.fr\/news\/#\/schema\/person\/070491b4b4fb7671bf59b3be20302ce9"},"breadcrumb":{"@id":"https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/#primaryimage","url":"https:\/\/www.gold.fr\/news\/wp-content\/uploads\/2025\/12\/ChatGPT-Image-19-dec.-2025-20_29_55.png","contentUrl":"https:\/\/www.gold.fr\/news\/wp-content\/uploads\/2025\/12\/ChatGPT-Image-19-dec.-2025-20_29_55.png","width":1536,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.gold.fr\/news\/2025\/12\/19\/les-banques-centrales-accumulent-mais-pas-pour-les-raisons-que-lon-croit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.gold.fr\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s","item":"https:\/\/www.gold.fr\/news\/"},{"@type":"ListItem","position":3,"name":"Les banques centrales accumulent, mais pas pour les raisons que l\u2019on croit"}]},{"@type":"WebSite","@id":"https:\/\/www.gold.fr\/news\/#website","url":"https:\/\/www.gold.fr\/news\/","name":"Gold.fr","description":"Actualit\u00e9s de l&#039;Or et des m\u00e9taux pr\u00e9cieux","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gold.fr\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.gold.fr\/news\/#\/schema\/person\/070491b4b4fb7671bf59b3be20302ce9","name":"Comptoir National de l'Or","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/0a2867fd5abe37bed95d5a65e9d58f01756e11efc68af9888dfc50cfa7f65948?s=96&d=mm&r=gb490554db0a38188709de567aa58480d","url":"https:\/\/secure.gravatar.com\/avatar\/0a2867fd5abe37bed95d5a65e9d58f01756e11efc68af9888dfc50cfa7f65948?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a2867fd5abe37bed95d5a65e9d58f01756e11efc68af9888dfc50cfa7f65948?s=96&d=mm&r=g","caption":"Comptoir National de l'Or"},"description":"Notre r\u00e9daction est constitu\u00e9e de membres experts dans les m\u00e9tiers de l'\u00e9conomie et la gestion, des Responsables d'agence Comptoir National de l'Or, des analystes financiers qui publient r\u00e9guli\u00e8rement des \u00e9tudes sur les politiques des banques centrales, le cours de l'or, prix de l'or, cours de l'argent, prix de l'argent, cours du platine, cours du palladium,... la situation en zone euro et l'impact de la strat\u00e9gie mon\u00e9taire de la FED. Notre \u00e9quipe scrute \u00e9galement une information plus g\u00e9n\u00e9raliste \u00e0 la recherche d'actualit\u00e9 \"p\u00e9pite\" \u00e0 vous partager. Depuis 5 ans, nous avons publi\u00e9 un peu plus de 4000 articles qui s'adressent \u00e0 un public large et vari\u00e9 ayant pour objectif de satisfaire votre curiosit\u00e9 et de partager avec vous une certaine fascination pour le m\u00e9tal jaune, le rachat d'or, et pour ceux qui veulent investir dans l'or, vendre leur or tout simplement en savoir plus... Pour tous vos achat or et argent, n'h\u00e9sitez pas \u00e0 prendre rendez-vous dans l'un de nos nombreux comptoirs.","sameAs":["https:\/\/www.gold.fr"]}]}},"authors":[{"term_id":2565,"user_id":18,"is_guest":0,"slug":"julie","display_name":"Comptoir National de l'Or","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/713f289e398d35ead876c4a4cc08607f0d6d266058cfc25683fffb6092d0e572?s=96&d=mm&r=g","author_category":"","first_name":"Comptoir National de l'Or","last_name":"","user_url":"https:\/\/www.gold.fr","job_title":"","description":"Notre r\u00e9daction est constitu\u00e9e de membres experts dans les m\u00e9tiers de l'\u00e9conomie et la gestion, des Responsables d'agence <a href=\"https:\/\/www.gold.fr\/a-propos\/\" title=\"tout savoir les comptoirs national de l'or\"><b>Comptoir National de l'Or<\/b><\/a>, des analystes financiers qui publient r\u00e9guli\u00e8rement des \u00e9tudes sur les politiques des <a href=\"https:\/\/www.gold.fr\/news\/article\/banque-centrale\/\">banques centrales<\/a>, le <a href=\"https:\/\/www.gold.fr\/cours-or-prix-de-l-or\/\" title=\"cours de l'or\"><b>cours de l'or, prix de l'or<\/b><\/a>, <a href=\"https:\/\/www.gold.fr\/cours-argent-prix-de-l-argent\/\">cours de l'argent, prix de l'argent<\/a>, <a href=\"https:\/\/www.gold.fr\/cours-platine-prix-du-platine\/\" title=\"cours du platine\">cours du platine<\/a>, <a href=\"https:\/\/www.gold.fr\/cours-palladium-prix-du-palladium\/\" title=\"cours du palladium\">cours du palladium<\/a>,... la situation en zone euro et l'impact de la strat\u00e9gie mon\u00e9taire de la <a href=\"https:\/\/www.gold.fr\/news\/article\/fed\/\">FED<\/a>. Notre \u00e9quipe scrute \u00e9galement une information plus g\u00e9n\u00e9raliste \u00e0 la recherche d'actualit\u00e9 \"p\u00e9pite\" \u00e0 vous partager. Depuis 5 ans, nous avons publi\u00e9 un peu plus de 4000 articles qui s'adressent \u00e0 un public large et vari\u00e9 ayant pour objectif de satisfaire votre curiosit\u00e9 et de partager avec vous une certaine fascination pour le <a href=\"https:\/\/www.gold.fr\/news\/article\/metal-jaune\/\">m\u00e9tal jaune<\/a>, le <a href=\"https:\/\/www.gold.fr\/rachat-bijoux-or-argent\/\">rachat d'or<\/a>, et pour ceux qui veulent <a href=\"https:\/\/www.gold.fr\/investir-dans-l-or\/\" title=\"investir Or\">investir dans l'or<\/a>, <a href=\"https:\/\/www.gold.fr\/vente-or\/\" title=\"vendre Or\">vendre leur or<\/a> tout simplement en savoir plus... Pour tous vos <a href=\"https:\/\/www.gold.fr\/achat-or-argent\/\" title=\"achat or et argent\">achat or et argent<\/a>, n'h\u00e9sitez pas \u00e0 prendre rendez-vous dans l'un de nos nombreux comptoirs."}],"_links":{"self":[{"href":"https:\/\/www.gold.fr\/news\/wp-json\/wp\/v2\/posts\/50292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gold.fr\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gold.fr\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gold.fr\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gold.fr\/news\/wp-json\/wp\/v2\/comments?post=50292"}],"version-history":[{"count":2,"href":"https:\/\/www.gold.fr\/news\/wp-json\/wp\/v2\/posts\/50292\/revisions"}],"predecessor-version":[{"id":50372,"href":"https:\/\/www.gold.fr\/news\/wp-json\/wp\/v2\/posts\/50292\/revisions\/50372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gold.fr\/news\/wp-json\/wp\/v2\/media\/50293"}],"wp:attachment":[{"href":"https:\/\/www.gold.fr\/news\/wp-json\/wp\/v2\/media?parent=50292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gold.fr\/news\/wp-json\/wp\/v2\/categories?post=50292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gold.fr\/news\/wp-json\/wp\/v2\/tags?post=50292"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.gold.fr\/news\/wp-json\/wp\/v2\/ppma_author?post=50292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}